{"id":4039,"date":"2024-03-20T14:08:04","date_gmt":"2024-03-20T13:08:04","guid":{"rendered":"https:\/\/www.laminierfolien.de\/shop\/?post_type=product&#038;p=4039"},"modified":"2024-05-22T12:12:11","modified_gmt":"2024-05-22T10:12:11","slug":"kaltlaminierfolien-300-mic-2x150","status":"publish","type":"product","link":"https:\/\/www.laminierfolien.de\/shop\/produkt\/kaltlaminierfolien-300-mic-2x150\/","title":{"rendered":"Kaltlaminierfolien &#8211; 300 Mic (2&#215;150)"},"content":{"rendered":"<p>Unsere Kaltlaminiertaschen sind perfekt f\u00fcr den schnellen Einsatz auch ohne Laminierger\u00e4t.<\/p>\n<p><strong>Eigenschaften dieser Laminierfolie:<\/strong><\/p>\n<p>&#x2714; verschiedene DIN-Gr\u00f6\u00dfen<br \/>\n&#x2714; Folienst\u00e4rke: 270 Mic (2 x 135),\u00a0 300 Mic (2 x 150)<br \/>\n&#x2714; kristallklare Oberfl\u00e4che f\u00fcr leuchtende und gl\u00e4nzende Farben<br \/>\n&#x2714; extrem rei\u00dffest und stabil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere Kaltlaminiertaschen sind perfekt f\u00fcr den schnellen Einsatz auch ohne Laminierger\u00e4t. Eigenschaften dieser Laminierfolie: &#x2714; verschiedene DIN-Gr\u00f6\u00dfen &#x2714; Folienst\u00e4rke: 270 Mic (2 x 135),\u00a0 300 Mic (2 x 150) &#x2714; kristallklare Oberfl\u00e4che f\u00fcr leuchtende und gl\u00e4nzende Farben &#x2714; extrem rei\u00dffest und stabil<\/p>\n","protected":false},"featured_media":4041,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[234,222],"product_tag":[362,300],"class_list":["post-4039","product","type-product","status-publish","has-post-thumbnail","product_cat-kaltlaminierfolien","product_cat-laminierfolien","product_tag-kaltlaminierfolien","product_tag-laminierfolien","pa_din-groesse-din-a3","pa_din-groesse-din-a4","pa_din-groesse-din-a5","pa_din-groesse-din-a6","pa_din-groesse-din-a7","pa_format-glaenzend","pa_format-glaenzend-langloch-kurze-seite","pa_format-glaenzend-langloch-lange-seite","pa_format-glaenzend-ohne-langloch","pa_staerke-300-mic-2x150","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/product\/4039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/comments?post=4039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/media\/4041"}],"wp:attachment":[{"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/product_brand?post=4039"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/product_cat?post=4039"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laminierfolien.de\/shop\/wp-json\/wp\/v2\/product_tag?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}